{"id":3541,"date":"2020-08-27T12:58:23","date_gmt":"2020-08-27T11:58:23","guid":{"rendered":"http:\/\/www.3bao.co.uk\/wordpress\/?p=3541"},"modified":"2020-08-27T13:09:10","modified_gmt":"2020-08-27T12:09:10","slug":"parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5","status":"publish","type":"post","link":"https:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/","title":{"rendered":"Parcelforce\u7cfb\u7edf\u7ef4\u62a4&#038;\u94f6\u884c\u5047\u65e5"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>\u5c0a\u656c\u7684\u5ba2\u6237\uff1a<\/p>\n\n\n\n<p>        \u4e3a\u4e86\u66f4\u597d\u7684\u63d0\u4f9b\u670d\u52a1\uff0cParcelforce\u8ba1\u5212\u4e8e8\u670830\u65e5\u661f\u671f\u65e5\u8fdb\u884c\u7cfb\u7edf\u7ef4\u62a4\uff0c\u57288\u670830\u65e5\u661f\u671f\u65e507:30\u523016:00\u5de6\u53f3\uff0c\u5728\u6b64\u671f\u95f4\u5c06\u6682\u505c\u51fa\u5355\u3002<\/p>\n\n\n\n<p>        8\u670831\u65e5 \u661f\u671f\u4e00 \u4e3a\u201cSummer Bank Holiday\u201d \u4ea6\u4e3a\u5047\u65e5\uff0c\u65e0\u6cd5\u9884\u8ba2\u53d6\u4ef6\uff0c\u8bf7\u63d0\u524d\u5b89\u6392\u597d\u5305\u88f9\u53d1\u9001\u3002<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5c0a\u656c\u7684\u5ba2\u6237\uff1a \u4e3a\u4e86\u66f4\u597d\u7684\u63d0\u4f9b\u670d\u52a1\uff0cPar<span class=\"more-link\"><a href=\"https:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/\"> &#8230;.<\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[63,48],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parcelforce\u7cfb\u7edf\u7ef4\u62a4&amp;\u94f6\u884c\u5047\u65e5 - \u4e09\u5b9d\u56fd\u9645\u901f\u9012-\u82f1\u56fd\u5230\u4e2d\u56fd\u7687\u5bb6\u90ae\u653f\u5feb\u9012<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce\u7cfb\u7edf\u7ef4\u62a4\u94f6\u884c\u5047\u65e5\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parcelforce\u7cfb\u7edf\u7ef4\u62a4&amp;\u94f6\u884c\u5047\u65e5 - \u4e09\u5b9d\u56fd\u9645\u901f\u9012-\u82f1\u56fd\u5230\u4e2d\u56fd\u7687\u5bb6\u90ae\u653f\u5feb\u9012\" \/>\n<meta property=\"og:description\" content=\"\u5c0a\u656c\u7684\u5ba2\u6237\uff1a \u4e3a\u4e86\u66f4\u597d\u7684\u63d0\u4f9b\u670d\u52a1\uff0cPar ....\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce\u7cfb\u7edf\u7ef4\u62a4\u94f6\u884c\u5047\u65e5\/\" \/>\n<meta property=\"og:site_name\" content=\"\u4e09\u5b9d\u56fd\u9645\u901f\u9012-\u82f1\u56fd\u5230\u4e2d\u56fd\u7687\u5bb6\u90ae\u653f\u5feb\u9012\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-27T11:58:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-27T12:09:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#organization\",\"name\":\"\\u4e09\\u5b9d\\u901f\\u9012\\uff08\\u661f\\u9a70\\u5feb\\u9012\\uff09\",\"url\":\"https:\/\/www.3bao.co.uk\/wordpress\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#logo\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/www.3bao.co.uk\/wordpress\/wp-content\/uploads\/2020\/06\/3bao_512.gif\",\"width\":512,\"height\":512,\"caption\":\"\\u4e09\\u5b9d\\u901f\\u9012\\uff08\\u661f\\u9a70\\u5feb\\u9012\\uff09\"},\"image\":{\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#website\",\"url\":\"https:\/\/www.3bao.co.uk\/wordpress\/\",\"name\":\"\\u4e09\\u5b9d\\u56fd\\u9645\\u901f\\u9012-\\u82f1\\u56fd\\u5230\\u4e2d\\u56fd\\u7687\\u5bb6\\u90ae\\u653f\\u5feb\\u9012\",\"description\":\"\\u4e09\\u5b9d\\u56fd\\u9645\\u901f\\u9012\\uff08\\u539f\\u661f\\u9a70\\u5feb\\u9012\\uff09\\u82f1\\u56fd\\u5230\\u4e2d\\u56fd\\u5927\\u9646\\uff0c\\u6e2f\\u6fb3\\u53f0\\u5730\\u533a\\u56fd\\u9645\\u7a7a\\u8fd0\\u548c\\u82f1\\u56fd\\u5883\\u5185\\u901f\\u9012\\u670d\\u52a1\\u3002\\u53ef\\u4ee5\\u76f4\\u90ae\\u5927\\u9646\\u5404\\u79cd\\u7269\\u54c1\\uff08\\u5305\\u62ec\\u5b66\\u751f\\u884c\\u674e\\uff0c\\u4e2a\\u4eba\\u7269\\u54c1\\uff0c\\u793c\\u54c1\\uff0c\\u4e2a\\u4eba\\u6d77\\u5916\\u4ee3\\u8d2d\\uff0c\\u5a74\\u513f\\u5976\\u7c89\\uff09\\uff0c\\u5a74\\u513f\\u5976\\u7c89\\u4ee3\\u6e05\\u5173\\u76f4\\u90ae\\u5927\\u9646\\u670d\\u52a1\\u3002\\u81ea\\u52a9\\u4e0b\\u5355\\u3002 \\u7687\\u5bb6\\u90ae\\u653f\\uff0c\\u8377\\u5170\\u90ae\\u653f\\u4e00\\u7ea7\\u4ee3\\u7406\\uff0c\\u4ef7\\u683c\\u4f18\\u60e0\\u3002\\u82f1\\u56fd\\u5168\\u7cfb\\u5976\\u7c89\\u7684\\u4ee3\\u8d2d\\u3002\\u4e13\\u4e1a\\u5305\\u88c5\\u7bb1\\uff0c\\u53cc\\u5c42\\u52a0\\u539a\\uff0c\\u7ed3\\u5b9e\\u8010\\u7528\\uff0c\\u8fd8\\u53ef\\u4ee5\\u62b5\\u6263\\u8fd0\\u8d39\\u3002\",\"publisher\":{\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.3bao.co.uk\/wordpress\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-CN\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/#webpage\",\"url\":\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/\",\"name\":\"Parcelforce\\u7cfb\\u7edf\\u7ef4\\u62a4&\\u94f6\\u884c\\u5047\\u65e5 - \\u4e09\\u5b9d\\u56fd\\u9645\\u901f\\u9012-\\u82f1\\u56fd\\u5230\\u4e2d\\u56fd\\u7687\\u5bb6\\u90ae\\u653f\\u5feb\\u9012\",\"isPartOf\":{\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#website\"},\"datePublished\":\"2020-08-27T11:58:23+00:00\",\"dateModified\":\"2020-08-27T12:09:10+00:00\",\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/\"]}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#\/schema\/person\/1db16f63d24005f93802b971621eb6ce\"},\"headline\":\"Parcelforce\\u7cfb\\u7edf\\u7ef4\\u62a4&#038;\\u94f6\\u884c\\u5047\\u65e5\",\"datePublished\":\"2020-08-27T11:58:23+00:00\",\"dateModified\":\"2020-08-27T12:09:10+00:00\",\"commentCount\":0,\"mainEntityOfPage\":{\"@id\":\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#organization\"},\"articleSection\":\"\\u516c\\u544a,\\u901a\\u77e5\",\"inLanguage\":\"zh-CN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/www.3bao.co.uk\/wordpress\/2020\/08\/27\/parcelforce%e7%b3%bb%e7%bb%9f%e7%bb%b4%e6%8a%a4%e9%93%b6%e8%a1%8c%e5%81%87%e6%97%a5\/#respond\"]}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#\/schema\/person\/1db16f63d24005f93802b971621eb6ce\",\"name\":\"chen, chen\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.3bao.co.uk\/wordpress\/#personlogo\",\"inLanguage\":\"zh-CN\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ec050b66dec36781dab56aa0290c48e7?s=96&d=mm&r=g\",\"caption\":\"chen, chen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/posts\/3541"}],"collection":[{"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/comments?post=3541"}],"version-history":[{"count":1,"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/posts\/3541\/revisions"}],"predecessor-version":[{"id":3542,"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/posts\/3541\/revisions\/3542"}],"wp:attachment":[{"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/media?parent=3541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/categories?post=3541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.3bao.co.uk\/wordpress\/wp-json\/wp\/v2\/tags?post=3541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}